{"id":974,"date":"2020-11-23T05:52:45","date_gmt":"2020-11-23T05:52:45","guid":{"rendered":"https:\/\/startertemplatecloud.com\/g02\/?page_id=974"},"modified":"2026-09-01T15:47:47","modified_gmt":"2026-09-01T15:47:47","slug":"ev","status":"publish","type":"page","link":"https:\/\/dgtl-planet.media\/turkce_iptv\/","title":{"rendered":"Ev"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_8e79e5-b6{margin-bottom:0px;}.kb-row-layout-id974_8e79e5-b6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_8e79e5-b6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_8e79e5-b6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:25%;padding-bottom:0%;min-height:400px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_8e79e5-b6 > .kt-row-layout-overlay{opacity:0.00;background-color:rgba(115, 13, 13, 0);}@media all and (max-width: 1024px){.kb-row-layout-id974_8e79e5-b6 > .kt-row-column-wrap{padding-top:0%;padding-right:0%;padding-bottom:30%;padding-left:0%;min-height:100px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id974_8e79e5-b6 > .kt-row-column-wrap{min-height:110px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_8e79e5-b6 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-blocks-carousel kb-blocks-bg-slider kt-carousel-container-dotstyle-none\"><div class=\"kt-blocks-carousel-init splide kb-blocks-bg-slider-init kt-carousel-arrowstyle-none kt-carousel-dotstyle-none\" data-slider-anim-speed=\"1000\" data-slider-type=\"slider\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"false\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-speed=\"4000\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-0\" style=\"background-image:url(https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/02\/THE-MOST-STABLE-IPTV-min.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-1\" style=\"background-image:url(https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/02\/3-min.png); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-2\" style=\"background-image:url(https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/02\/2-min.png); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-3\" style=\"background-image:url(https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/02\/4-min.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-4\" style=\"background-image:url(https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/02\/5-min.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><\/ul><\/div><\/div><\/div><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column974_68a3f9-e3 > .kt-inside-inner-col,.kadence-column974_68a3f9-e3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_68a3f9-e3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_68a3f9-e3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_68a3f9-e3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_68a3f9-e3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_68a3f9-e3{position:relative;}@media all and (max-width: 1024px){.kadence-column974_68a3f9-e3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_68a3f9-e3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_68a3f9-e3 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_796d01-5e{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id974_796d01-5e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_796d01-5e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_796d01-5e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_796d01-5e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id974_796d01-5e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id974_796d01-5e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_796d01-5e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_bc5216-19 > .kt-inside-inner-col{padding-top:66px;}.kadence-column974_bc5216-19 > .kt-inside-inner-col,.kadence-column974_bc5216-19 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_bc5216-19 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_bc5216-19 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_bc5216-19 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_bc5216-19 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_bc5216-19{position:relative;}@media all and (max-width: 1024px){.kadence-column974_bc5216-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_bc5216-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_bc5216-19 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns974_56b8a1-2b, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns974_56b8a1-2b, .wp-block-kadence-advancedbtn.kb-btns974_56b8a1-2b, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns974_56b8a1-2b{margin-top:-40px;margin-bottom:-50px;}.wp-block-kadence-advancedbtn.kb-btns974_56b8a1-2b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_56b8a1-2b .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns974_56b8a1-2b{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns974_56b8a1-2b{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_56b8a1-2b\"><style>.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button{width:188px;}.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button{color:var(--global-palette9, #ffffff);background:#39a8f0;font-weight:bold;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;box-shadow:1px 2px 2px 3px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette9, #ffffff);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;box-shadow:2px 2px 2px 1px var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_757b25-8d.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_757b25-8d kt-btn-size-standard kt-btn-width-type-fixed kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.com\/shop\/?add-to-cart=1990\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Try it Free!<\/span><\/a>\n\n<style>.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button{width:188px;}.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button{color:var(--global-palette9, #ffffff);background:#39a8f0;font-weight:bold;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;box-shadow:1px 2px 2px 3px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette9, #ffffff);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;box-shadow:2px 2px 2px 1px var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_3c12ff-ce.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_3c12ff-ce kt-btn-size-standard kt-btn-width-type-fixed kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#plans\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">SEE OUR PLANS<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column974_f26b97-b7 > .kt-inside-inner-col{padding-top:2em;}.kadence-column974_f26b97-b7 > .kt-inside-inner-col,.kadence-column974_f26b97-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_f26b97-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f26b97-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f26b97-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f26b97-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f26b97-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f26b97-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f26b97-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f26b97-b7\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-carousel-slider-slider\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-6042\" style=\"--carousel-slider-nav-color:rgba(241,241,241,0);--carousel-slider-active-nav-color:rgba(0,209,178,0);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-6042\" class=\"carousel-slider carousel-slider-6042 arrows-visibility-never dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":false,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":5000,\"autoplaySpeed\":500,\"autoplayHoverPause\":false,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":5},\"576\":{\"items\":6},\"768\":{\"items\":8},\"1024\":{\"items\":9},\"1280\":{\"items\":10},\"1536\":{\"items\":12}}}'>\n<div class=\"carousel-slider__item\">\n\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-38.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-38.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-38-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-38-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-17.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-17.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-17-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-17-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-29.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-29.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-29-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-29-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-33.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-33.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-33-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-33-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-18.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-18.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-18-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-18-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-39.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-39.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-39-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-39-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-41.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-41.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-41-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-41-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-7.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-7.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-7-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-7-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-36.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-36.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-36-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-36-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-6.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-6.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-6-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-6-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-32.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-32.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-32-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-32-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-21.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-21.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-21-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-21-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-37.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-37.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-37-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-37-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-12.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-12.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-12-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-12-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-15.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-15.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-15-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-15-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-20.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-20.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-20-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-20-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-22.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-22.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-22-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-22-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-34.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-34.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-34-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-34-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-13.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-13.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-13-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-13-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-1.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-1-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-1-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-10.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-10.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-10-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-10-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-26.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-26.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-26-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-26-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-9.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-9.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-9-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-9-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-35.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-35.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-35-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-35-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-2.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-2-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-2-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-16.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-16.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-16-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-16-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-42.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-42.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-42-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-42-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-25.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-25.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-25-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-25-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-23.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-23.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-23-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-23-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-28.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-28.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-28-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-28-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-31.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-31.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-31-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-31-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-30.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-30.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-30-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-30-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-19.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-19.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-19-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-19-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-40.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-40.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-40-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-40-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-43.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-43.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-43-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-43-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-8.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-8.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-8-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-8-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-3.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-3.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-3-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-3-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-4.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-4.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-4-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-4-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-14.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-14.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-14-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-14-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-27.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-27.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-27-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-27-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-5.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-5.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-5-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-5-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-11.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-11.png 501w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-11-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-11-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-24.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-24.png 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-24-300x300.png 300w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/01-24-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<\/div><!-- .carousel-slider-6042 -->\n<\/div><!-- .carousel-slider-outer-6042 -->\n<\/div>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:50px;padding-bottom:0px;}.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_03d587-a4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_03d587-a4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_03d587-a4 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column974_d53bd4-47 > .kt-inside-inner-col,.kadence-column974_d53bd4-47 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_d53bd4-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_d53bd4-47 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_d53bd4-47 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_d53bd4-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_d53bd4-47{position:relative;}@media all and (max-width: 1024px){.kadence-column974_d53bd4-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_d53bd4-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_d53bd4-47 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:10px;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_15b7a1-b8.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_15b7a1-b8 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_15b7a1-b8 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_15b7a1-b8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_15b7a1-b8 .kt-info-svg-icon-flip, .kt-info-box974_15b7a1-b8 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_15b7a1-b8 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_15b7a1-b8 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}@media all and (max-width: 767px){.kt-info-box974_15b7a1-b8 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_15b7a1-b8\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/4-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4373\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Top Rated Channels<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Enjoy Top-rated TV channels with the best streaming experience.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_cbcc88-8b > .kt-inside-inner-col,.kadence-column974_cbcc88-8b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_cbcc88-8b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_cbcc88-8b > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_cbcc88-8b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_cbcc88-8b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_cbcc88-8b{position:relative;}@media all and (max-width: 1024px){.kadence-column974_cbcc88-8b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_cbcc88-8b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_cbcc88-8b inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_a5c53f-cb.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_a5c53f-cb .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_a5c53f-cb .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_a5c53f-cb .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_a5c53f-cb .kt-info-svg-icon-flip, .kt-info-box974_a5c53f-cb .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_a5c53f-cb .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_a5c53f-cb .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_a5c53f-cb .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box974_a5c53f-cb .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_a5c53f-cb\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/3-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4369\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Fast Connected<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Once you sign up whether a Free Trial or a Paid Plan. You get instant access with the same login credentials.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_9522ed-54 > .kt-inside-inner-col,.kadence-column974_9522ed-54 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_9522ed-54 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_9522ed-54 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_9522ed-54 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_9522ed-54 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_9522ed-54{position:relative;}@media all and (max-width: 1024px){.kadence-column974_9522ed-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_9522ed-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_9522ed-54 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_c37b3a-86.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_c37b3a-86 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_c37b3a-86 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_c37b3a-86 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_c37b3a-86 .kt-info-svg-icon-flip, .kt-info-box974_c37b3a-86 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_c37b3a-86 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_c37b3a-86 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_c37b3a-86 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box974_c37b3a-86 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_c37b3a-86\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/2-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4365\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Customer Service<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Get 24 hours 7 days a week Customer Service<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_dc3b6f-00 > .kt-inside-inner-col,.kadence-column974_dc3b6f-00 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_dc3b6f-00 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_dc3b6f-00 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_dc3b6f-00 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_dc3b6f-00 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_dc3b6f-00{position:relative;}@media all and (max-width: 1024px){.kadence-column974_dc3b6f-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_dc3b6f-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_dc3b6f-00 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:20px;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_9abf4c-e3.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_9abf4c-e3 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_9abf4c-e3 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_9abf4c-e3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_9abf4c-e3 .kt-info-svg-icon-flip, .kt-info-box974_9abf4c-e3 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_9abf4c-e3 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_9abf4c-e3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_9abf4c-e3 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_9abf4c-e3\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/5-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4376\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Best Pricing Plans<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">You will not find a second place to save money with such Quality Standards.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col,.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col{background-color:rgba(49, 130, 206, 0);}.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_ac9a3f-d0{position:relative;}@media all and (max-width: 1024px){.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_ac9a3f-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_ac9a3f-d0\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-carousel-slider-slider\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-6093\" style=\"--carousel-slider-nav-color:rgba(241,241,241,0);--carousel-slider-active-nav-color:rgba(0,209,178,0);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-6093\" class=\"carousel-slider carousel-slider-6093 arrows-visibility-hover dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":true,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":1500,\"autoplaySpeed\":700,\"autoplayHoverPause\":false,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":2},\"576\":{\"items\":3},\"768\":{\"items\":3},\"1024\":{\"items\":4},\"1280\":{\"items\":5},\"1536\":{\"items\":5}}}'>\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Killing-Eve-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Killing-Eve-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Killing-Eve-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-French-Dispatch-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-French-Dispatch-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-French-Dispatch-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Good-Omens-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Good-Omens-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Good-Omens-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Card-Counter-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Card-Counter-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Card-Counter-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/This-Is-Going-to-Hurt-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/This-Is-Going-to-Hurt-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/This-Is-Going-to-Hurt-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Power-of-the-Dog-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Power-of-the-Dog-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Power-of-the-Dog-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Ghosts-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Ghosts-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Ghosts-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Mr.-Bean-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Mr.-Bean-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Mr.-Bean-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Inside-Man-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Inside-Man-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Inside-Man-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Doc-Martin-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Doc-Martin-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Doc-Martin-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Puss-in-Boots-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Puss-in-Boots-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Puss-in-Boots-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/His-Dark-Materials-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/His-Dark-Materials-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/His-Dark-Materials-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Happy-Valley-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Happy-Valley-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Happy-Valley-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Lost-City-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Lost-City-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Lost-City-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Man-vs.-Bee-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Man-vs.-Bee-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Man-vs.-Bee-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Peaky-Blinders-imdb-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Peaky-Blinders-imdb-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Peaky-Blinders-imdb-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Aquaman-and-the-Lost-Kingdom-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Aquaman-and-the-Lost-Kingdom-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Aquaman-and-the-Lost-Kingdom-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Top-Gear-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Top-Gear-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Top-Gear-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Stay-Close-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Stay-Close-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Stay-Close-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Bad-Guys-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Bad-Guys-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Bad-Guys-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Thor-Love-and-Thunder-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Thor-Love-and-Thunder-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Thor-Love-and-Thunder-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Detectorists-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Detectorists-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Detectorists-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Game-of-Thrones-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Game-of-Thrones-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Game-of-Thrones-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Bubble-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Bubble-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Bubble-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/White-Lines-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/White-Lines-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/White-Lines-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Nightingale-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Nightingale-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Nightingale-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/After-Life-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/After-Life-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/After-Life-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Mission-Impossible-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Mission-Impossible-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Mission-Impossible-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Luther-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Luther-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Luther-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Unbearable-Weight-of-Massive-Talent-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Unbearable-Weight-of-Massive-Talent-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Unbearable-Weight-of-Massive-Talent-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Jurassic-World-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Jurassic-World-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Jurassic-World-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Broadchurch-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Broadchurch-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Broadchurch-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Nevers-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Nevers-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Nevers-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Northman-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Northman-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Northman-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Red-Notice-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Red-Notice-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Red-Notice-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-English-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-English-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-English-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fantastic-Beasts-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fantastic-Beasts-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fantastic-Beasts-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Last-Duel-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Last-Duel-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Last-Duel-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Batman-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Batman-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Batman-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Bad-Sisters-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Bad-Sisters-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Bad-Sisters-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Avatar-2-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Avatar-2-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Avatar-2-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/No-Time-to-Die-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/No-Time-to-Die-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/No-Time-to-Die-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Menu-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Menu-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Menu-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Tourist-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Tourist-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Tourist-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Sonic-the-Hedgehog-2-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Sonic-the-Hedgehog-2-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Sonic-the-Hedgehog-2-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Clarksons-Farm-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Clarksons-Farm-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Clarksons-Farm-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Slow-Horses-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Slow-Horses-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Slow-Horses-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Sandman-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Sandman-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Sandman-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Malignant-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Malignant-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Malignant-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Spencer-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Spencer-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Spencer-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Responder-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Responder-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Responder-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Doctor-Strange-in-the-Multiverse-of-Madness-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Doctor-Strange-in-the-Multiverse-of-Madness-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Doctor-Strange-in-the-Multiverse-of-Madness-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Man-in-the-High-Castle-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Man-in-the-High-Castle-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Man-in-the-High-Castle-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Crown-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Crown-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Crown-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Line-of-Duty-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Line-of-Duty-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Line-of-Duty-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/the-god-father-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/the-god-father-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/the-god-father-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-355-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-355-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-355-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-End-of-the-Fucking-World-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-End-of-the-Fucking-World-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-End-of-the-Fucking-World-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Panther-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Panther-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Panther-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Devils-Hour-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Devils-Hour-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Devils-Hour-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Prison-Break-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Prison-Break-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Prison-Break-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Nightmare-Alley-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Nightmare-Alley-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Nightmare-Alley-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Indiana-Jones-5-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Indiana-Jones-5-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Indiana-Jones-5-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Benediction-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Benediction-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Benediction-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Heartstopper-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Heartstopper-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Heartstopper-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/elvis-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/elvis-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/elvis-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Many-Saints-of-Newark-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Many-Saints-of-Newark-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Many-Saints-of-Newark-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/SAS-Rogue-Heroes-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/SAS-Rogue-Heroes-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/SAS-Rogue-Heroes-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fleabag-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fleabag-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fleabag-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Endeavour-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Endeavour-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Endeavour-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Cyrano-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Cyrano-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Cyrano-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fate-The-Winx-Saga-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fate-The-Winx-Saga-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Fate-The-Winx-Saga-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Adam-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Adam-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Adam-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Last-Kingdom-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Last-Kingdom-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/The-Last-Kingdom-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Hotel-Portofino-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Hotel-Portofino-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Hotel-Portofino-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Mirror-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Mirror-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Black-Mirror-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Matilda-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Matilda-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Matilda-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/A-Discovery-of-Witches-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/A-Discovery-of-Witches-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/A-Discovery-of-Witches-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Derry-Girls-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Derry-Girls-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Derry-Girls-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Last-Night-in-Soho-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Last-Night-in-Soho-min.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/04\/Last-Night-in-Soho-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<\/div><!-- .carousel-slider-6093 -->\n<\/div><!-- .carousel-slider-outer-6093 -->\n<\/div>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-id974_794876-8b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_794876-8b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_794876-8b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:0px;}.kb-row-layout-id974_794876-8b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_794876-8b > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_794876-8b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id974_794876-8b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_794876-8b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id974_794876-8b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_794876-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_794876-8b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column974_f8c2f9-df > .kt-inside-inner-col,.kadence-column974_f8c2f9-df > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_f8c2f9-df > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f8c2f9-df > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f8c2f9-df > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f8c2f9-df > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f8c2f9-df{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f8c2f9-df > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f8c2f9-df > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f8c2f9-df inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:10px;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_4b4e3c-e2.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_4b4e3c-e2 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_4b4e3c-e2 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_4b4e3c-e2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_4b4e3c-e2 .kt-info-svg-icon-flip, .kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_4b4e3c-e2 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_4b4e3c-e2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}@media all and (max-width: 767px){.kt-info-box974_4b4e3c-e2 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_4b4e3c-e2\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/6-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4379\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>67000+ VOD<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">More than 67000 VOD films and series in multiple languages.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_38b911-f2 > .kt-inside-inner-col,.kadence-column974_38b911-f2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_38b911-f2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_38b911-f2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_38b911-f2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_38b911-f2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_38b911-f2{position:relative;}@media all and (max-width: 1024px){.kadence-column974_38b911-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_38b911-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_38b911-f2 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_c477c6-dc.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_c477c6-dc .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_c477c6-dc .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_c477c6-dc .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_c477c6-dc .kt-info-svg-icon-flip, .kt-info-box974_c477c6-dc .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_c477c6-dc .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_c477c6-dc .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_c477c6-dc .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_c477c6-dc .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box974_c477c6-dc .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_c477c6-dc\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/1-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4362\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>19000+ CHANNELS<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Full customizable channel list.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_e2bd59-da > .kt-inside-inner-col,.kadence-column974_e2bd59-da > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_e2bd59-da > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_e2bd59-da > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_e2bd59-da > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_e2bd59-da > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_e2bd59-da{position:relative;}@media all and (max-width: 1024px){.kadence-column974_e2bd59-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_e2bd59-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_e2bd59-da inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_66ec3a-42.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_66ec3a-42 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_66ec3a-42 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_66ec3a-42 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_66ec3a-42 .kt-info-svg-icon-flip, .kt-info-box974_66ec3a-42 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_66ec3a-42 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_66ec3a-42 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_66ec3a-42 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box974_66ec3a-42 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_66ec3a-42\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/10-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4384\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>99.99% UPTIME<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">All live channels are 99.99% uptime.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_86afad-e6 > .kt-inside-inner-col,.kadence-column974_86afad-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_86afad-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_86afad-e6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_86afad-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_86afad-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_86afad-e6{position:relative;}@media all and (max-width: 1024px){.kadence-column974_86afad-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_86afad-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_86afad-e6 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:20px;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box974_bb6a75-34.wp-block-kadence-infobox{max-width:100%;}.kt-info-box974_bb6a75-34 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box974_bb6a75-34 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box974_bb6a75-34 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box974_bb6a75-34 .kt-info-svg-icon-flip, .kt-info-box974_bb6a75-34 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box974_bb6a75-34 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box974_bb6a75-34 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box974_bb6a75-34 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box974_bb6a75-34 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box974_bb6a75-34\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2022\/09\/8-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4381\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Refund Guaranteed<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">check our <a href=\"https:\/\/dgtl-planet.media\/refund_returns\/\" data-type=\"URL\" data-id=\"https:\/\/prim-iptv.com\/refund_returns\/\">refund policy<\/a>.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_3f71b8-34{margin-top:-20px;}.kb-row-layout-id974_3f71b8-34 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_3f71b8-34 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_3f71b8-34 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_3f71b8-34 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id974_3f71b8-34 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id974_3f71b8-34 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_3f71b8-34 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column974_9bdeea-d9 > .kt-inside-inner-col,.kadence-column974_9bdeea-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_9bdeea-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_9bdeea-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_9bdeea-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_9bdeea-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_9bdeea-d9{position:relative;}.kadence-column974_9bdeea-d9, .kt-inside-inner-col > .kadence-column974_9bdeea-d9:not(.specificity){margin-top:-20px;}@media all and (max-width: 1024px){.kadence-column974_9bdeea-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_9bdeea-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_9bdeea-d9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id974_f34125-c0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_f34125-c0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_f34125-c0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:700px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_f34125-c0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id974_f34125-c0 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id974_f34125-c0 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_f34125-c0 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_ac45d6-63 > .kt-inside-inner-col{padding-top:40px;}.kadence-column974_ac45d6-63 > .kt-inside-inner-col,.kadence-column974_ac45d6-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_ac45d6-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_ac45d6-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_ac45d6-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_ac45d6-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_ac45d6-63{position:relative;}@media all and (max-width: 1024px){.kadence-column974_ac45d6-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_ac45d6-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_ac45d6-63 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32, .wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32[data-kb-block=\"kb-adv-heading974_b755e4-32\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);margin-top:10px;margin-bottom:40px;text-align:center;font-size:46px;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32[data-kb-block=\"kb-adv-heading974_b755e4-32\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32[data-kb-block=\"kb-adv-heading974_b755e4-32\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32, .wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32[data-kb-block=\"kb-adv-heading974_b755e4-32\"]{font-size:40px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32, .wp-block-kadence-advancedheading.kt-adv-heading974_b755e4-32[data-kb-block=\"kb-adv-heading974_b755e4-32\"]{font-size:30px;}}<\/style>\n<h2 class=\"kt-adv-heading974_b755e4-32 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading974_b755e4-32\">Choose A Subscription Plan<\/h2>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id974_99ed11-41 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_99ed11-41 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_99ed11-41 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0%;padding-bottom:0%;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_99ed11-41 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id974_99ed11-41 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id974_99ed11-41 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_99ed11-41 alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_6f7211-a6 > .kt-inside-inner-col{padding-top:0%;padding-right:20%;padding-left:20%;}.kadence-column974_6f7211-a6 > .kt-inside-inner-col,.kadence-column974_6f7211-a6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_6f7211-a6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_6f7211-a6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_6f7211-a6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_6f7211-a6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_6f7211-a6{position:relative;}@media all and (max-width: 1024px){.kadence-column974_6f7211-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_6f7211-a6 > .kt-inside-inner-col{padding-right:5%;padding-left:5%;flex-direction:column;justify-content:center;}.kadence-column974_6f7211-a6, .kt-inside-inner-col > .kadence-column974_6f7211-a6:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_6f7211-a6 kvs-lg-false kvs-md-false kvs-sm-false inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column974_fd6ade-1e > .kt-inside-inner-col{padding-top:0px;}.kadence-column974_fd6ade-1e > .kt-inside-inner-col,.kadence-column974_fd6ade-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_fd6ade-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_fd6ade-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_fd6ade-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_fd6ade-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_fd6ade-1e{position:relative;}.kadence-column974_fd6ade-1e, .kt-inside-inner-col > .kadence-column974_fd6ade-1e:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kadence-column974_fd6ade-1e > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column974_fd6ade-1e, .kt-inside-inner-col > .kadence-column974_fd6ade-1e:not(.specificity){margin-top:0px;}}@media all and (max-width: 767px){.kadence-column974_fd6ade-1e > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}.kadence-column974_fd6ade-1e, .kt-inside-inner-col > .kadence-column974_fd6ade-1e:not(.specificity){margin-top:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_fd6ade-1e inner-column-1\" id=\"plans\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_b7ca1c-99{margin-top:0px;}.kb-row-layout-id974_b7ca1c-99 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_b7ca1c-99 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_b7ca1c-99 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_b7ca1c-99{background-image:url('https:\/\/dgtl-space.com\/wp-content\/uploads\/2022\/10\/Ew0RYacVkAoMmNO-1.webp');background-size:cover;background-position:50% 100%;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id974_b7ca1c-99 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg,var(--global-palette9,#ffffff) 0%,rgba(26,32,44,0) 17%,rgba(0,0,0,0) 91%,var(--global-palette9,#ffffff) 100%);mix-blend-mode:normal;}@media all and (min-width: 1025px){.kb-row-layout-id974_b7ca1c-99{display:none !important;}}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id974_b7ca1c-99{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id974_b7ca1c-99 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_b7ca1c-99{margin-top:0px;}.kb-row-layout-id974_b7ca1c-99 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id974_b7ca1c-99 {nn}n<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_b7ca1c-99 alignfull kb-v-lg-hidden kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column974_6edebd-f2 > .kt-inside-inner-col{display:flex;}.kadence-column974_6edebd-f2 > .kt-inside-inner-col,.kadence-column974_6edebd-f2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_6edebd-f2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_6edebd-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column974_6edebd-f2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column974_6edebd-f2{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_6edebd-f2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_6edebd-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column974_6edebd-f2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_6edebd-f2{position:relative;}.kadence-column974_6edebd-f2, .kt-inside-inner-col > .kadence-column974_6edebd-f2:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column974_6edebd-f2{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_6edebd-f2{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_6edebd-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column974_6edebd-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column974_6edebd-f2{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_6edebd-f2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_6edebd-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column974_6edebd-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_6edebd-f2 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-tabs-id974_3e3028-42 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-title-list li{margin-top:0px;margin-right:5px;margin-bottom:0px;margin-left:5px;}.wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-family:-apple-system,BlinkMacSystemFont,\"Segoe UI\",Roboto,Oxygen-Sans,Ubuntu,Cantarell,\"Helvetica Neue\",sans-serif, \"Apple Color Emoji\", \"Segoe UI Emoji\", \"Segoe UI Symbol\";font-weight:600;font-style:normal;border-top-width:2px;border-right-width:2px;border-bottom-width:2px;border-left-width:2px;border-top-left-radius:22px;border-top-right-radius:22px;border-bottom-right-radius:22px;border-bottom-left-radius:22px;border-color:var(--global-palette2, #2B6CB0);color:var(--global-palette2, #2B6CB0);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:5px;margin-bottom:0px;margin-left:5px;}.wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:rgba(255,255,255,0);color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);}.wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id974_3e3028-42 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:rgba(56,38,61,0);color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);}<\/style>\n<div class=\"wp-block-kadence-tabs alignfull\"><div class=\"kt-tabs-wrap kt-tabs-id974_3e3028-42 kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-center \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-1device\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-1device\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">1 Device<\/span><\/a><\/li><li id=\"tab-2devices\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-2devices\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">2 Devices<\/span><\/a><\/li><li id=\"tab-3devices\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-3devices\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">3 Devices<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tabd00f0a-53\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_5ada56-e1 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_5ada56-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id974_5ada56-e1 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_5ada56-e1 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_52b29e-b9 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_52b29e-b9 > .kt-inside-inner-col,.kadence-column974_52b29e-b9 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_52b29e-b9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_52b29e-b9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_52b29e-b9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_52b29e-b9 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_52b29e-b9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_52b29e-b9{position:relative;}@media all and (max-width: 1024px){.kadence-column974_52b29e-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_52b29e-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_52b29e-b9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_750eb3-04, .wp-block-kadence-advancedheading.kt-adv-heading974_750eb3-04[data-kb-block=\"kb-adv-heading974_750eb3-04\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_750eb3-04 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_750eb3-04[data-kb-block=\"kb-adv-heading974_750eb3-04\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_750eb3-04 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_750eb3-04[data-kb-block=\"kb-adv-heading974_750eb3-04\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_750eb3-04 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_750eb3-04\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color wp-block-paragraph\"><s>\u00a315<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_c2ada5-09, .wp-block-kadence-advancedheading.kt-adv-heading974_c2ada5-09[data-kb-block=\"kb-adv-heading974_c2ada5-09\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_c2ada5-09 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_c2ada5-09[data-kb-block=\"kb-adv-heading974_c2ada5-09\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_c2ada5-09 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_c2ada5-09[data-kb-block=\"kb-adv-heading974_c2ada5-09\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_c2ada5-09 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_c2ada5-09\"><strong>\u00a39.99<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b626d7-8c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b626d7-8c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b626d7-8c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b626d7-8c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_b626d7-8c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_b626d7-8c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_b626d7-8c kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_ef0101-33 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_ef0101-33 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_ef0101-33 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_d4bad0-be .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d4bad0-be .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d4bad0-be kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_b9a986-56 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b9a986-56 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b9a986-56 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_dc91ee-b6 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_dc91ee-b6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_dc91ee-b6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_76e36d-d5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_76e36d-d5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_76e36d-d5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_0fbc5f-c9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_0fbc5f-c9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_0fbc5f-c9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_f061b0-17.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_f061b0-17 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false &lt;script&gt; var metaTag = document.createElement(&#039;meta&#039;); metaTag.name &quot;referrer&quot;; metaTag.content &quot;no-referrer&quot;; document.getElementsByTagName(&#039;head&#039;)[0].appendChild(metaTag); &lt;\/script&gt; wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_520a1a-4e > .kt-inside-inner-col,.kadence-column974_520a1a-4e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_520a1a-4e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_520a1a-4e > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_520a1a-4e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_520a1a-4e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_520a1a-4e{position:relative;}@media all and (max-width: 1024px){.kadence-column974_520a1a-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_520a1a-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_520a1a-4e inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_57b949-b7 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_57b949-b7 > .kt-inside-inner-col,.kadence-column974_57b949-b7 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_57b949-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_57b949-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_57b949-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_57b949-b7 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_57b949-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_57b949-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column974_57b949-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_57b949-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_57b949-b7 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_ee7a2e-c9, .wp-block-kadence-advancedheading.kt-adv-heading974_ee7a2e-c9[data-kb-block=\"kb-adv-heading974_ee7a2e-c9\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_ee7a2e-c9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_ee7a2e-c9[data-kb-block=\"kb-adv-heading974_ee7a2e-c9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_ee7a2e-c9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_ee7a2e-c9[data-kb-block=\"kb-adv-heading974_ee7a2e-c9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_ee7a2e-c9 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_ee7a2e-c9\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>30<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_e9b1d4-59, .wp-block-kadence-advancedheading.kt-adv-heading974_e9b1d4-59[data-kb-block=\"kb-adv-heading974_e9b1d4-59\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_e9b1d4-59 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_e9b1d4-59[data-kb-block=\"kb-adv-heading974_e9b1d4-59\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_e9b1d4-59 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_e9b1d4-59[data-kb-block=\"kb-adv-heading974_e9b1d4-59\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_e9b1d4-59 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_e9b1d4-59\"><strong>\u00a320<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_3eb57c-cc:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_3eb57c-cc ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_3eb57c-cc ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_3eb57c-cc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_3eb57c-cc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_3eb57c-cc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_3eb57c-cc kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_629c2b-7e .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_629c2b-7e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_629c2b-7e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_1e1d73-b2 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_1e1d73-b2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_1e1d73-b2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_d2e10e-b1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d2e10e-b1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d2e10e-b1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_d02784-db .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d02784-db .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d02784-db kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_4b658c-2c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_4b658c-2c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_4b658c-2c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_aca9f7-cb{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_aca9f7-cb .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_aca9f7-cb\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_5d2934-e3.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_5d2934-e3 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_37eb9d-46 > .kt-inside-inner-col,.kadence-column974_37eb9d-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_37eb9d-46 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_37eb9d-46 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_37eb9d-46 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_37eb9d-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_37eb9d-46{position:relative;}@media all and (max-width: 1024px){.kadence-column974_37eb9d-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_37eb9d-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_37eb9d-46 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_53868c-99 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_53868c-99 > .kt-inside-inner-col,.kadence-column974_53868c-99 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_53868c-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_53868c-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_53868c-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_53868c-99 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_53868c-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_53868c-99{position:relative;}@media all and (max-width: 1024px){.kadence-column974_53868c-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_53868c-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_53868c-99 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_fa1257-eb, .wp-block-kadence-advancedheading.kt-adv-heading974_fa1257-eb[data-kb-block=\"kb-adv-heading974_fa1257-eb\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_fa1257-eb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_fa1257-eb[data-kb-block=\"kb-adv-heading974_fa1257-eb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_fa1257-eb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_fa1257-eb[data-kb-block=\"kb-adv-heading974_fa1257-eb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_fa1257-eb wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_fa1257-eb\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>45<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_01aa2b-cb, .wp-block-kadence-advancedheading.kt-adv-heading974_01aa2b-cb[data-kb-block=\"kb-adv-heading974_01aa2b-cb\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_01aa2b-cb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_01aa2b-cb[data-kb-block=\"kb-adv-heading974_01aa2b-cb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_01aa2b-cb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_01aa2b-cb[data-kb-block=\"kb-adv-heading974_01aa2b-cb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_01aa2b-cb wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_01aa2b-cb\"><strong>\u00a340<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_093aa1-51:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_093aa1-51 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_093aa1-51 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_093aa1-51 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_093aa1-51 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_093aa1-51 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_093aa1-51 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_72dccc-41 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_72dccc-41 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_72dccc-41 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_aa29e2-cd .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_aa29e2-cd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_aa29e2-cd kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_206414-27 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_206414-27 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_206414-27 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6cda2a-94 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6cda2a-94 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6cda2a-94 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_331369-51 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_331369-51 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_331369-51 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_93fe6e-ec{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_93fe6e-ec .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_93fe6e-ec\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_c59a5d-65.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_c59a5d-65 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_8f9fef-f4 > .kt-inside-inner-col,.kadence-column974_8f9fef-f4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_8f9fef-f4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_8f9fef-f4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_8f9fef-f4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_8f9fef-f4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_8f9fef-f4{position:relative;}@media all and (max-width: 1024px){.kadence-column974_8f9fef-f4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_8f9fef-f4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_8f9fef-f4 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_85e5ea-01 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_85e5ea-01 > .kt-inside-inner-col,.kadence-column974_85e5ea-01 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_85e5ea-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_85e5ea-01 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_85e5ea-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_85e5ea-01 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_85e5ea-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_85e5ea-01{position:relative;}@media all and (max-width: 1024px){.kadence-column974_85e5ea-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_85e5ea-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_85e5ea-01 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_1b17bc-8a, .wp-block-kadence-advancedheading.kt-adv-heading974_1b17bc-8a[data-kb-block=\"kb-adv-heading974_1b17bc-8a\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_1b17bc-8a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_1b17bc-8a[data-kb-block=\"kb-adv-heading974_1b17bc-8a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_1b17bc-8a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_1b17bc-8a[data-kb-block=\"kb-adv-heading974_1b17bc-8a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_1b17bc-8a wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_1b17bc-8a\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>70<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_4450a4-43, .wp-block-kadence-advancedheading.kt-adv-heading974_4450a4-43[data-kb-block=\"kb-adv-heading974_4450a4-43\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_4450a4-43 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_4450a4-43[data-kb-block=\"kb-adv-heading974_4450a4-43\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_4450a4-43 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_4450a4-43[data-kb-block=\"kb-adv-heading974_4450a4-43\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_4450a4-43 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_4450a4-43\"><strong>\u00a350<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7ab034-1b:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7ab034-1b ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7ab034-1b ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7ab034-1b ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_7ab034-1b ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_7ab034-1b ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_7ab034-1b kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_5ea84d-3e .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_5ea84d-3e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_5ea84d-3e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_df6633-35 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_df6633-35 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_df6633-35 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_049e4a-eb .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_049e4a-eb .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_049e4a-eb kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_97ccc3-62 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_97ccc3-62 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_97ccc3-62 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_46bbca-ce .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_46bbca-ce .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_46bbca-ce kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_a9a980-88{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_a9a980-88 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_a9a980-88\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_63dd6d-2e.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_63dd6d-2e kt-btn-size-small kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab7963e7-d9\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_c97093-18 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_c97093-18 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id974_c97093-18 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_c97093-18 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_7a3bca-d6 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_7a3bca-d6 > .kt-inside-inner-col,.kadence-column974_7a3bca-d6 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_7a3bca-d6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_7a3bca-d6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_7a3bca-d6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_7a3bca-d6 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_7a3bca-d6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_7a3bca-d6{position:relative;}@media all and (max-width: 1024px){.kadence-column974_7a3bca-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_7a3bca-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_7a3bca-d6 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_fd524e-24, .wp-block-kadence-advancedheading.kt-adv-heading974_fd524e-24[data-kb-block=\"kb-adv-heading974_fd524e-24\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_fd524e-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_fd524e-24[data-kb-block=\"kb-adv-heading974_fd524e-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_fd524e-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_fd524e-24[data-kb-block=\"kb-adv-heading974_fd524e-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_fd524e-24 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_fd524e-24\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>20<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_285343-57, .wp-block-kadence-advancedheading.kt-adv-heading974_285343-57[data-kb-block=\"kb-adv-heading974_285343-57\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_285343-57 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_285343-57[data-kb-block=\"kb-adv-heading974_285343-57\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_285343-57 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_285343-57[data-kb-block=\"kb-adv-heading974_285343-57\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_285343-57 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_285343-57\"><strong><s>\u00a3<\/s><\/strong>15<\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_2253b6-da:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_2253b6-da ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_2253b6-da ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_2253b6-da ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_2253b6-da ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_2253b6-da ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_2253b6-da kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_86134e-4b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_86134e-4b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_86134e-4b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_ada0ba-2f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_ada0ba-2f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_ada0ba-2f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_8fd58c-fa .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_8fd58c-fa .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_8fd58c-fa kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_b7d88d-f3 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b7d88d-f3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b7d88d-f3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_757cb2-93 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_757cb2-93 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_757cb2-93 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_5f575a-3f{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_5f575a-3f .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_5f575a-3f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_b0ffce-8c.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_b0ffce-8c kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_771a39-ea > .kt-inside-inner-col,.kadence-column974_771a39-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_771a39-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_771a39-ea > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_771a39-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_771a39-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_771a39-ea{position:relative;}@media all and (max-width: 1024px){.kadence-column974_771a39-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_771a39-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_771a39-ea inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_4cea9e-e9 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_4cea9e-e9 > .kt-inside-inner-col,.kadence-column974_4cea9e-e9 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_4cea9e-e9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_4cea9e-e9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_4cea9e-e9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_4cea9e-e9 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_4cea9e-e9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_4cea9e-e9{position:relative;}@media all and (max-width: 1024px){.kadence-column974_4cea9e-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_4cea9e-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_4cea9e-e9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_f09e1e-43, .wp-block-kadence-advancedheading.kt-adv-heading974_f09e1e-43[data-kb-block=\"kb-adv-heading974_f09e1e-43\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_f09e1e-43 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_f09e1e-43[data-kb-block=\"kb-adv-heading974_f09e1e-43\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_f09e1e-43 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_f09e1e-43[data-kb-block=\"kb-adv-heading974_f09e1e-43\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_f09e1e-43 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_f09e1e-43\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>40<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_10e4a4-b2, .wp-block-kadence-advancedheading.kt-adv-heading974_10e4a4-b2[data-kb-block=\"kb-adv-heading974_10e4a4-b2\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_10e4a4-b2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_10e4a4-b2[data-kb-block=\"kb-adv-heading974_10e4a4-b2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_10e4a4-b2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_10e4a4-b2[data-kb-block=\"kb-adv-heading974_10e4a4-b2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_10e4a4-b2 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_10e4a4-b2\"><strong><s>\u00a3<\/s>30<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_04ab31-64:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_04ab31-64 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_04ab31-64 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_04ab31-64 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_04ab31-64 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_04ab31-64 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_04ab31-64 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_553db5-8a .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_553db5-8a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_553db5-8a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_b68088-d7 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b68088-d7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b68088-d7 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_ae3cf1-98 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_ae3cf1-98 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_ae3cf1-98 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e4a237-30 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e4a237-30 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e4a237-30 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_d51a77-81 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d51a77-81 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d51a77-81 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_9ee4c8-8f{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_9ee4c8-8f .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_9ee4c8-8f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_d82c34-e4.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_d82c34-e4 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_3934ef-cd > .kt-inside-inner-col,.kadence-column974_3934ef-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_3934ef-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_3934ef-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_3934ef-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_3934ef-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_3934ef-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column974_3934ef-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_3934ef-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_3934ef-cd inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_63caa0-fb > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_63caa0-fb > .kt-inside-inner-col,.kadence-column974_63caa0-fb > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_63caa0-fb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_63caa0-fb > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_63caa0-fb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_63caa0-fb > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_63caa0-fb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_63caa0-fb{position:relative;}@media all and (max-width: 1024px){.kadence-column974_63caa0-fb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_63caa0-fb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_63caa0-fb inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_ed44e9-11, .wp-block-kadence-advancedheading.kt-adv-heading974_ed44e9-11[data-kb-block=\"kb-adv-heading974_ed44e9-11\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_ed44e9-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_ed44e9-11[data-kb-block=\"kb-adv-heading974_ed44e9-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_ed44e9-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_ed44e9-11[data-kb-block=\"kb-adv-heading974_ed44e9-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_ed44e9-11 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_ed44e9-11\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>80<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_3385bc-1b, .wp-block-kadence-advancedheading.kt-adv-heading974_3385bc-1b[data-kb-block=\"kb-adv-heading974_3385bc-1b\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_3385bc-1b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_3385bc-1b[data-kb-block=\"kb-adv-heading974_3385bc-1b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_3385bc-1b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_3385bc-1b[data-kb-block=\"kb-adv-heading974_3385bc-1b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_3385bc-1b wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_3385bc-1b\"><strong><s>\u00a3<\/s>60<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7182e8-77:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7182e8-77 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7182e8-77 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_7182e8-77 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_7182e8-77 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_7182e8-77 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_7182e8-77 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_ca5648-89 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_ca5648-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_ca5648-89 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f43809-a8 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f43809-a8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f43809-a8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_b5368e-99 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b5368e-99 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b5368e-99 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_357469-92 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_357469-92 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_357469-92 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_82a43a-d0 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_82a43a-d0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_82a43a-d0 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_ca7670-d4{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_ca7670-d4 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_ca7670-d4\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8ddad1-27.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_8ddad1-27 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_59b8a5-65 > .kt-inside-inner-col,.kadence-column974_59b8a5-65 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_59b8a5-65 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_59b8a5-65 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_59b8a5-65 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_59b8a5-65 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_59b8a5-65{position:relative;}@media all and (max-width: 1024px){.kadence-column974_59b8a5-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_59b8a5-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_59b8a5-65 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_530de5-33 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_530de5-33 > .kt-inside-inner-col,.kadence-column974_530de5-33 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_530de5-33 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_530de5-33 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_530de5-33 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_530de5-33 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_530de5-33 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_530de5-33{position:relative;}@media all and (max-width: 1024px){.kadence-column974_530de5-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_530de5-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_530de5-33 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_0310ac-8c, .wp-block-kadence-advancedheading.kt-adv-heading974_0310ac-8c[data-kb-block=\"kb-adv-heading974_0310ac-8c\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_0310ac-8c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_0310ac-8c[data-kb-block=\"kb-adv-heading974_0310ac-8c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_0310ac-8c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_0310ac-8c[data-kb-block=\"kb-adv-heading974_0310ac-8c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_0310ac-8c wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_0310ac-8c\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>100<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_6c1c8c-0c, .wp-block-kadence-advancedheading.kt-adv-heading974_6c1c8c-0c[data-kb-block=\"kb-adv-heading974_6c1c8c-0c\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_6c1c8c-0c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_6c1c8c-0c[data-kb-block=\"kb-adv-heading974_6c1c8c-0c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_6c1c8c-0c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_6c1c8c-0c[data-kb-block=\"kb-adv-heading974_6c1c8c-0c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_6c1c8c-0c wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_6c1c8c-0c\"><strong><s>\u00a3<\/s>80<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_451e61-3a:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_451e61-3a ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_451e61-3a ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_451e61-3a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_451e61-3a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_451e61-3a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_451e61-3a kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_06b21f-44 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_06b21f-44 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_06b21f-44 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_efd7df-7b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_efd7df-7b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_efd7df-7b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_5dbe53-6d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_5dbe53-6d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_5dbe53-6d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_763e66-16 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_763e66-16 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_763e66-16 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_4371cd-9d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_4371cd-9d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_4371cd-9d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_d80593-59{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_d80593-59 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_d80593-59\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_3f3ed5-8f.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_3f3ed5-8f kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tabdc252b-cc\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_09cac9-4c > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_09cac9-4c > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id974_09cac9-4c .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_09cac9-4c alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_9c6a97-5b > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_9c6a97-5b > .kt-inside-inner-col,.kadence-column974_9c6a97-5b > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_9c6a97-5b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_9c6a97-5b > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_9c6a97-5b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_9c6a97-5b > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_9c6a97-5b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_9c6a97-5b{position:relative;}@media all and (max-width: 1024px){.kadence-column974_9c6a97-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_9c6a97-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_9c6a97-5b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_b0dcf6-f9, .wp-block-kadence-advancedheading.kt-adv-heading974_b0dcf6-f9[data-kb-block=\"kb-adv-heading974_b0dcf6-f9\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_b0dcf6-f9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_b0dcf6-f9[data-kb-block=\"kb-adv-heading974_b0dcf6-f9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_b0dcf6-f9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_b0dcf6-f9[data-kb-block=\"kb-adv-heading974_b0dcf6-f9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_b0dcf6-f9 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_b0dcf6-f9\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>30<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_85cb19-0e, .wp-block-kadence-advancedheading.kt-adv-heading974_85cb19-0e[data-kb-block=\"kb-adv-heading974_85cb19-0e\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_85cb19-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_85cb19-0e[data-kb-block=\"kb-adv-heading974_85cb19-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_85cb19-0e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_85cb19-0e[data-kb-block=\"kb-adv-heading974_85cb19-0e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_85cb19-0e wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_85cb19-0e\"><strong><s>\u00a3<\/s>22<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f313fd-dc:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f313fd-dc ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f313fd-dc ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f313fd-dc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_f313fd-dc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_f313fd-dc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_f313fd-dc kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_ee8cc0-b9 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_ee8cc0-b9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_ee8cc0-b9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_71f80e-76 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_71f80e-76 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_71f80e-76 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_1e38c5-e0 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_1e38c5-e0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_1e38c5-e0 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_d01a28-d1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d01a28-d1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d01a28-d1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_612132-c9 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_612132-c9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_612132-c9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_5116b1-e8{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_5116b1-e8 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_5116b1-e8\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_f28e6d-79.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_f28e6d-79 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_a0f09e-34 > .kt-inside-inner-col,.kadence-column974_a0f09e-34 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_a0f09e-34 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_a0f09e-34 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_a0f09e-34 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_a0f09e-34 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_a0f09e-34{position:relative;}@media all and (max-width: 1024px){.kadence-column974_a0f09e-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_a0f09e-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_a0f09e-34 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_52eaac-b8 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_52eaac-b8 > .kt-inside-inner-col,.kadence-column974_52eaac-b8 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_52eaac-b8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_52eaac-b8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_52eaac-b8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_52eaac-b8 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_52eaac-b8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_52eaac-b8{position:relative;}@media all and (max-width: 1024px){.kadence-column974_52eaac-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_52eaac-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_52eaac-b8 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_78d111-50, .wp-block-kadence-advancedheading.kt-adv-heading974_78d111-50[data-kb-block=\"kb-adv-heading974_78d111-50\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_78d111-50 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_78d111-50[data-kb-block=\"kb-adv-heading974_78d111-50\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_78d111-50 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_78d111-50[data-kb-block=\"kb-adv-heading974_78d111-50\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_78d111-50 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_78d111-50\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>60<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_31d4da-5d, .wp-block-kadence-advancedheading.kt-adv-heading974_31d4da-5d[data-kb-block=\"kb-adv-heading974_31d4da-5d\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_31d4da-5d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_31d4da-5d[data-kb-block=\"kb-adv-heading974_31d4da-5d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_31d4da-5d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_31d4da-5d[data-kb-block=\"kb-adv-heading974_31d4da-5d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_31d4da-5d wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_31d4da-5d\"><strong><s>\u00a3<\/s>45<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_1442e8-ff:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_1442e8-ff ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_1442e8-ff ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_1442e8-ff ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_1442e8-ff ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_1442e8-ff ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_1442e8-ff kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_d23f3a-ac .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d23f3a-ac .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d23f3a-ac kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_79e79f-99 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_79e79f-99 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_79e79f-99 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_fc162f-01 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_fc162f-01 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_fc162f-01 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6b37ad-ab .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6b37ad-ab .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6b37ad-ab kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_7fc937-d0 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_7fc937-d0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_7fc937-d0 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_5c0b32-98{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_5c0b32-98 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_5c0b32-98\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_b89496-3a.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_b89496-3a kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_f76199-90 > .kt-inside-inner-col,.kadence-column974_f76199-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_f76199-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f76199-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f76199-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f76199-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f76199-90{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f76199-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f76199-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f76199-90 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_f6b39c-de > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_f6b39c-de > .kt-inside-inner-col,.kadence-column974_f6b39c-de > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_f6b39c-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f6b39c-de > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f6b39c-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f6b39c-de > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_f6b39c-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f6b39c-de{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f6b39c-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f6b39c-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f6b39c-de inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_bcb542-b7, .wp-block-kadence-advancedheading.kt-adv-heading974_bcb542-b7[data-kb-block=\"kb-adv-heading974_bcb542-b7\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_bcb542-b7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_bcb542-b7[data-kb-block=\"kb-adv-heading974_bcb542-b7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_bcb542-b7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_bcb542-b7[data-kb-block=\"kb-adv-heading974_bcb542-b7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_bcb542-b7 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_bcb542-b7\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>120<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_c8a778-e7, .wp-block-kadence-advancedheading.kt-adv-heading974_c8a778-e7[data-kb-block=\"kb-adv-heading974_c8a778-e7\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_c8a778-e7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_c8a778-e7[data-kb-block=\"kb-adv-heading974_c8a778-e7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_c8a778-e7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_c8a778-e7[data-kb-block=\"kb-adv-heading974_c8a778-e7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_c8a778-e7 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_c8a778-e7\"><strong><s>\u00a3<\/s><\/strong>90<\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_5b434d-4e:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_5b434d-4e ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_5b434d-4e ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_5b434d-4e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_5b434d-4e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_5b434d-4e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_5b434d-4e kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_15b245-79 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_15b245-79 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_15b245-79 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_b81aea-4b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b81aea-4b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b81aea-4b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c5bcec-47 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c5bcec-47 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c5bcec-47 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_1077b1-0f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_1077b1-0f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_1077b1-0f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_7ccd78-33 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_7ccd78-33 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_7ccd78-33 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_df9e86-bb{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_df9e86-bb .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_df9e86-bb\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_9ed039-87.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_9ed039-87 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_331148-36 > .kt-inside-inner-col,.kadence-column974_331148-36 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_331148-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_331148-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_331148-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_331148-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_331148-36{position:relative;}@media all and (max-width: 1024px){.kadence-column974_331148-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_331148-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_331148-36 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_f57ac5-23 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_f57ac5-23 > .kt-inside-inner-col,.kadence-column974_f57ac5-23 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_f57ac5-23 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f57ac5-23 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f57ac5-23 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f57ac5-23 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_f57ac5-23 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f57ac5-23{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f57ac5-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f57ac5-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f57ac5-23 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_69051c-61, .wp-block-kadence-advancedheading.kt-adv-heading974_69051c-61[data-kb-block=\"kb-adv-heading974_69051c-61\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_69051c-61 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_69051c-61[data-kb-block=\"kb-adv-heading974_69051c-61\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_69051c-61 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_69051c-61[data-kb-block=\"kb-adv-heading974_69051c-61\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_69051c-61 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_69051c-61\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>150<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_af3016-bc, .wp-block-kadence-advancedheading.kt-adv-heading974_af3016-bc[data-kb-block=\"kb-adv-heading974_af3016-bc\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_af3016-bc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_af3016-bc[data-kb-block=\"kb-adv-heading974_af3016-bc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_af3016-bc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_af3016-bc[data-kb-block=\"kb-adv-heading974_af3016-bc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_af3016-bc wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_af3016-bc\"><strong><s>\u00a3<\/s>110<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_8e67f9-21:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_8e67f9-21 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_8e67f9-21 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_8e67f9-21 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_8e67f9-21 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_8e67f9-21 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_8e67f9-21 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_bd36e0-89 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_bd36e0-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_bd36e0-89 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_8d7959-48 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_8d7959-48 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_8d7959-48 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c9354f-71 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c9354f-71 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c9354f-71 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_cdd1a5-58 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_cdd1a5-58 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_cdd1a5-58 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_aba35a-4d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_aba35a-4d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_aba35a-4d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_9ad513-fe{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_9ad513-fe .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_9ad513-fe\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:16px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_214140-43.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_214140-43 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_05ca68-b8{margin-top:0px;}.kb-row-layout-id974_05ca68-b8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_05ca68-b8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_05ca68-b8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_05ca68-b8{background-image:url('https:\/\/dgtl-space.com\/wp-content\/uploads\/2022\/10\/Ew0RYacVkAoMmNO-1.webp');background-size:cover;background-position:50% 100%;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id974_05ca68-b8 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg,var(--global-palette9,#ffffff) 5%,rgba(26,32,44,0) 30%,rgba(0,0,0,0) 88%,var(--global-palette9,#ffffff) 100%);mix-blend-mode:normal;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id974_05ca68-b8{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id974_05ca68-b8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id974_05ca68-b8{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id974_05ca68-b8{margin-top:0px;}.kb-row-layout-id974_05ca68-b8 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_05ca68-b8{display:none !important;}}.kb-row-layout-id974_05ca68-b8 {nn}n<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_05ca68-b8 alignfull kb-v-md-hidden kb-v-sm-hidden kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column974_64dc08-a9 > .kt-inside-inner-col{display:flex;}.kadence-column974_64dc08-a9 > .kt-inside-inner-col,.kadence-column974_64dc08-a9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_64dc08-a9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_64dc08-a9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column974_64dc08-a9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column974_64dc08-a9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_64dc08-a9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_64dc08-a9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column974_64dc08-a9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_64dc08-a9{position:relative;}.kadence-column974_64dc08-a9, .kt-inside-inner-col > .kadence-column974_64dc08-a9:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column974_64dc08-a9{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_64dc08-a9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_64dc08-a9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column974_64dc08-a9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column974_64dc08-a9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_64dc08-a9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column974_64dc08-a9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column974_64dc08-a9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_64dc08-a9 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid rgba(188,188,188,0);border-right:0px solid rgba(188,188,188,0);border-bottom:0px solid rgba(188,188,188,0);border-left:0px solid rgba(188,188,188,0);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-title-list li{margin-top:0px;margin-right:5px;margin-bottom:0px;margin-left:5px;}.wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-family:-apple-system,BlinkMacSystemFont,\"Segoe UI\",Roboto,Oxygen-Sans,Ubuntu,Cantarell,\"Helvetica Neue\",sans-serif, \"Apple Color Emoji\", \"Segoe UI Emoji\", \"Segoe UI Symbol\";font-weight:600;font-style:normal;border-top-width:2px;border-right-width:2px;border-bottom-width:2px;border-left-width:2px;border-top-left-radius:22px;border-top-right-radius:22px;border-bottom-right-radius:22px;border-bottom-left-radius:22px;border-color:var(--global-palette2, #2B6CB0);color:var(--global-palette2, #2B6CB0);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:5px;margin-bottom:0px;margin-left:5px;}.wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:rgba(255,255,255,0);color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);}.wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:rgba(56,38,61,0);color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid rgba(188,188,188,0);border-right:0px solid rgba(188,188,188,0);border-bottom:0px solid rgba(188,188,188,0);border-left:0px solid rgba(188,188,188,0);}}@media all and (max-width: 767px){.kt-tabs-id974_033254-2d > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid rgba(188,188,188,0);border-right:0px solid rgba(188,188,188,0);border-bottom:0px solid rgba(188,188,188,0);border-left:0px solid rgba(188,188,188,0);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignfull\"><div class=\"kt-tabs-wrap kt-tabs-id974_033254-2d kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-center \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-1device\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-1device\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">1 Device<\/span><\/a><\/li><li id=\"tab-2devices\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-2devices\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">2 Devices<\/span><\/a><\/li><li id=\"tab-3devices\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-3devices\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">3 Devices<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab3110ea-2d\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_fa7472-dc > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_fa7472-dc > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id974_fa7472-dc .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_fa7472-dc alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_1f7024-21 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_1f7024-21 > .kt-inside-inner-col,.kadence-column974_1f7024-21 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_1f7024-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_1f7024-21 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_1f7024-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_1f7024-21 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_1f7024-21 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_1f7024-21{position:relative;}@media all and (max-width: 1024px){.kadence-column974_1f7024-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_1f7024-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_1f7024-21 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_d9029f-10, .wp-block-kadence-advancedheading.kt-adv-heading974_d9029f-10[data-kb-block=\"kb-adv-heading974_d9029f-10\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_d9029f-10 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_d9029f-10[data-kb-block=\"kb-adv-heading974_d9029f-10\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_d9029f-10 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_d9029f-10[data-kb-block=\"kb-adv-heading974_d9029f-10\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_d9029f-10 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_d9029f-10\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color wp-block-paragraph\"><s>\u00a315<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_2c26cc-11, .wp-block-kadence-advancedheading.kt-adv-heading974_2c26cc-11[data-kb-block=\"kb-adv-heading974_2c26cc-11\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_2c26cc-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_2c26cc-11[data-kb-block=\"kb-adv-heading974_2c26cc-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_2c26cc-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_2c26cc-11[data-kb-block=\"kb-adv-heading974_2c26cc-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_2c26cc-11 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_2c26cc-11\"><strong>\u00a39.99<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_22fd3d-61:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_22fd3d-61 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_22fd3d-61 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_22fd3d-61 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_22fd3d-61 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_22fd3d-61 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_22fd3d-61 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_bcf176-a1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_bcf176-a1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_bcf176-a1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_3e57c9-a4 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_3e57c9-a4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_3e57c9-a4 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_ff3dce-7b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_ff3dce-7b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_ff3dce-7b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_32d542-e8 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_32d542-e8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_32d542-e8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_0f2a1e-58 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_0f2a1e-58 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_0f2a1e-58 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_dc9c5b-4b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_dc9c5b-4b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_dc9c5b-4b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_4dfa2a-02 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_4dfa2a-02 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_4dfa2a-02 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_60917f-e4 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_60917f-e4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_60917f-e4 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_179ba0-a5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_179ba0-a5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_179ba0-a5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_ab996d-8a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_ab996d-8a .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_ab996d-8a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:20px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_cf7588-5e.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_cf7588-5e kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_9812f0-7b > .kt-inside-inner-col,.kadence-column974_9812f0-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_9812f0-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_9812f0-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_9812f0-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_9812f0-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_9812f0-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column974_9812f0-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_9812f0-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_9812f0-7b inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_eaf34b-d4 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_eaf34b-d4 > .kt-inside-inner-col,.kadence-column974_eaf34b-d4 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_eaf34b-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_eaf34b-d4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_eaf34b-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_eaf34b-d4 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_eaf34b-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_eaf34b-d4{position:relative;}@media all and (max-width: 1024px){.kadence-column974_eaf34b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_eaf34b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_eaf34b-d4 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_8e89af-2d, .wp-block-kadence-advancedheading.kt-adv-heading974_8e89af-2d[data-kb-block=\"kb-adv-heading974_8e89af-2d\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_8e89af-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_8e89af-2d[data-kb-block=\"kb-adv-heading974_8e89af-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_8e89af-2d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_8e89af-2d[data-kb-block=\"kb-adv-heading974_8e89af-2d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_8e89af-2d wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_8e89af-2d\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>30<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_a0c7e0-d1, .wp-block-kadence-advancedheading.kt-adv-heading974_a0c7e0-d1[data-kb-block=\"kb-adv-heading974_a0c7e0-d1\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_a0c7e0-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_a0c7e0-d1[data-kb-block=\"kb-adv-heading974_a0c7e0-d1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_a0c7e0-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_a0c7e0-d1[data-kb-block=\"kb-adv-heading974_a0c7e0-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_a0c7e0-d1 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_a0c7e0-d1\"><strong>\u00a320<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_cc92cc-88:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_cc92cc-88 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_cc92cc-88 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_cc92cc-88 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_cc92cc-88 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_cc92cc-88 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_cc92cc-88 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_b31827-9e .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b31827-9e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b31827-9e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_831017-e1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_831017-e1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_831017-e1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_97a4c9-c6 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_97a4c9-c6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_97a4c9-c6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_4d1e2c-c0 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_4d1e2c-c0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_4d1e2c-c0 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_34688b-75 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_34688b-75 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_34688b-75 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_8662d1-cc .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_8662d1-cc .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_8662d1-cc kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_9977a0-fe .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_9977a0-fe .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_9977a0-fe kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c5803f-fe .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c5803f-fe .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c5803f-fe kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_63e68a-1c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_63e68a-1c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_63e68a-1c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_0b23d1-b9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_0b23d1-b9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_0b23d1-b9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:20px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8f861b-18.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_8f861b-18 kt-btn-size-small kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_7c9e4e-8b > .kt-inside-inner-col,.kadence-column974_7c9e4e-8b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_7c9e4e-8b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_7c9e4e-8b > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_7c9e4e-8b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_7c9e4e-8b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_7c9e4e-8b{position:relative;}@media all and (max-width: 1024px){.kadence-column974_7c9e4e-8b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_7c9e4e-8b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_7c9e4e-8b inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_f57733-7f > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_f57733-7f > .kt-inside-inner-col,.kadence-column974_f57733-7f > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_f57733-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f57733-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f57733-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f57733-7f > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_f57733-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f57733-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f57733-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f57733-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f57733-7f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_5ac075-46, .wp-block-kadence-advancedheading.kt-adv-heading974_5ac075-46[data-kb-block=\"kb-adv-heading974_5ac075-46\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_5ac075-46 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_5ac075-46[data-kb-block=\"kb-adv-heading974_5ac075-46\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_5ac075-46 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_5ac075-46[data-kb-block=\"kb-adv-heading974_5ac075-46\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_5ac075-46 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_5ac075-46\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>45<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_c1b71d-2f, .wp-block-kadence-advancedheading.kt-adv-heading974_c1b71d-2f[data-kb-block=\"kb-adv-heading974_c1b71d-2f\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_c1b71d-2f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_c1b71d-2f[data-kb-block=\"kb-adv-heading974_c1b71d-2f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_c1b71d-2f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_c1b71d-2f[data-kb-block=\"kb-adv-heading974_c1b71d-2f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_c1b71d-2f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_c1b71d-2f\"><strong>\u00a340<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b563c7-51:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b563c7-51 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b563c7-51 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b563c7-51 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_b563c7-51 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_b563c7-51 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_b563c7-51 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_88b1bb-83 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_88b1bb-83 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_88b1bb-83 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6409b0-e5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6409b0-e5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6409b0-e5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_3b5e5c-ec .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_3b5e5c-ec .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_3b5e5c-ec kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_788224-83 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_788224-83 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_788224-83 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_87ecff-00 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_87ecff-00 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_87ecff-00 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e325e9-76 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e325e9-76 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e325e9-76 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e15400-e5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e15400-e5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e15400-e5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_335785-d5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_335785-d5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_335785-d5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f43e3a-3c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f43e3a-3c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f43e3a-3c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_086eb4-c6{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_086eb4-c6 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_086eb4-c6\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:20px;font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_8b7147-5e.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_8b7147-5e kt-btn-size-small kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_330c57-17 > .kt-inside-inner-col,.kadence-column974_330c57-17 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_330c57-17 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_330c57-17 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_330c57-17 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_330c57-17 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_330c57-17{position:relative;}@media all and (max-width: 1024px){.kadence-column974_330c57-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_330c57-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_330c57-17 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_a26c62-fe > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_a26c62-fe > .kt-inside-inner-col,.kadence-column974_a26c62-fe > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_a26c62-fe > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_a26c62-fe > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_a26c62-fe > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_a26c62-fe > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_a26c62-fe > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_a26c62-fe{position:relative;}@media all and (max-width: 1024px){.kadence-column974_a26c62-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_a26c62-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_a26c62-fe inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_ad21a1-dd, .wp-block-kadence-advancedheading.kt-adv-heading974_ad21a1-dd[data-kb-block=\"kb-adv-heading974_ad21a1-dd\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_ad21a1-dd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_ad21a1-dd[data-kb-block=\"kb-adv-heading974_ad21a1-dd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_ad21a1-dd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_ad21a1-dd[data-kb-block=\"kb-adv-heading974_ad21a1-dd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_ad21a1-dd wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_ad21a1-dd\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>70<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_2feeb1-5f, .wp-block-kadence-advancedheading.kt-adv-heading974_2feeb1-5f[data-kb-block=\"kb-adv-heading974_2feeb1-5f\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_2feeb1-5f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_2feeb1-5f[data-kb-block=\"kb-adv-heading974_2feeb1-5f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_2feeb1-5f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_2feeb1-5f[data-kb-block=\"kb-adv-heading974_2feeb1-5f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_2feeb1-5f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_2feeb1-5f\"><strong>\u00a350<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_47703d-41:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_47703d-41 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_47703d-41 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_47703d-41 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_47703d-41 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_47703d-41 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_47703d-41 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_dc3bb0-78 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_dc3bb0-78 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_dc3bb0-78 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_484679-0e .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_484679-0e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_484679-0e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_039f6f-22 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_039f6f-22 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_039f6f-22 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e7fd04-0c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e7fd04-0c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e7fd04-0c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6a3874-8b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6a3874-8b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6a3874-8b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_00e837-e9 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_00e837-e9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_00e837-e9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6f7910-cf .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6f7910-cf .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6f7910-cf kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_263fa4-f4 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_263fa4-f4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_263fa4-f4 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_2c8553-ab .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_2c8553-ab .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_2c8553-ab kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_b547d0-db{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_b547d0-db .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_b547d0-db\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_ac6a90-e9.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_ac6a90-e9 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab2b3b1b-48\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_f45f98-6d > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_f45f98-6d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id974_f45f98-6d .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_f45f98-6d alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_daef3a-ed > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_daef3a-ed > .kt-inside-inner-col,.kadence-column974_daef3a-ed > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_daef3a-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_daef3a-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_daef3a-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_daef3a-ed > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_daef3a-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_daef3a-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column974_daef3a-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_daef3a-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_daef3a-ed inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_1a7dc2-d0, .wp-block-kadence-advancedheading.kt-adv-heading974_1a7dc2-d0[data-kb-block=\"kb-adv-heading974_1a7dc2-d0\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_1a7dc2-d0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_1a7dc2-d0[data-kb-block=\"kb-adv-heading974_1a7dc2-d0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_1a7dc2-d0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_1a7dc2-d0[data-kb-block=\"kb-adv-heading974_1a7dc2-d0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_1a7dc2-d0 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_1a7dc2-d0\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>20<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_3f9194-54, .wp-block-kadence-advancedheading.kt-adv-heading974_3f9194-54[data-kb-block=\"kb-adv-heading974_3f9194-54\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_3f9194-54 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_3f9194-54[data-kb-block=\"kb-adv-heading974_3f9194-54\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_3f9194-54 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_3f9194-54[data-kb-block=\"kb-adv-heading974_3f9194-54\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_3f9194-54 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_3f9194-54\"><strong><s>\u00a3<\/s><\/strong>15<\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_30ef74-07:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_30ef74-07 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_30ef74-07 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_30ef74-07 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_30ef74-07 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_30ef74-07 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_30ef74-07 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_6c6444-24 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6c6444-24 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6c6444-24 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_a5c8e8-d4 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_a5c8e8-d4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_a5c8e8-d4 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_2fb651-0c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_2fb651-0c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_2fb651-0c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_2f0470-61 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_2f0470-61 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_2f0470-61 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_115d19-9c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_115d19-9c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_115d19-9c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_7dcce9-76 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_7dcce9-76 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_7dcce9-76 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_0e9b9b-36 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_0e9b9b-36 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_0e9b9b-36 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f30aa6-9a .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f30aa6-9a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f30aa6-9a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c55567-c6 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c55567-c6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c55567-c6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_1bef27-aa{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_1bef27-aa .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_1bef27-aa\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_245d99-95.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_245d99-95 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_9b6502-85 > .kt-inside-inner-col,.kadence-column974_9b6502-85 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_9b6502-85 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_9b6502-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_9b6502-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_9b6502-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_9b6502-85{position:relative;}@media all and (max-width: 1024px){.kadence-column974_9b6502-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_9b6502-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_9b6502-85 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_7c6983-f9 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_7c6983-f9 > .kt-inside-inner-col,.kadence-column974_7c6983-f9 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_7c6983-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_7c6983-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_7c6983-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_7c6983-f9 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_7c6983-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_7c6983-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column974_7c6983-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_7c6983-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_7c6983-f9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_6cd941-f4, .wp-block-kadence-advancedheading.kt-adv-heading974_6cd941-f4[data-kb-block=\"kb-adv-heading974_6cd941-f4\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_6cd941-f4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_6cd941-f4[data-kb-block=\"kb-adv-heading974_6cd941-f4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_6cd941-f4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_6cd941-f4[data-kb-block=\"kb-adv-heading974_6cd941-f4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_6cd941-f4 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_6cd941-f4\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>40<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_3cacf0-04, .wp-block-kadence-advancedheading.kt-adv-heading974_3cacf0-04[data-kb-block=\"kb-adv-heading974_3cacf0-04\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_3cacf0-04 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_3cacf0-04[data-kb-block=\"kb-adv-heading974_3cacf0-04\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_3cacf0-04 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_3cacf0-04[data-kb-block=\"kb-adv-heading974_3cacf0-04\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_3cacf0-04 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_3cacf0-04\"><strong><s>\u00a3<\/s>30<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_9ff142-ab:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_9ff142-ab ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_9ff142-ab ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_9ff142-ab ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_9ff142-ab ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_9ff142-ab ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_9ff142-ab kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_cee393-83 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_cee393-83 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_cee393-83 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_edce79-b9 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_edce79-b9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_edce79-b9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f4e39c-c8 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f4e39c-c8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f4e39c-c8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_61e012-0e .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_61e012-0e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_61e012-0e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_db9551-1d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_db9551-1d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_db9551-1d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_bb3edd-ea .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_bb3edd-ea .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_bb3edd-ea kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_cc224b-c5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_cc224b-c5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_cc224b-c5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_0bffcc-5c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_0bffcc-5c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_0bffcc-5c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_5a348b-e2 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_5a348b-e2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_5a348b-e2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_f4eab6-04{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_f4eab6-04 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_f4eab6-04\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_86ab41-2b.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_86ab41-2b kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_e2b911-fe > .kt-inside-inner-col,.kadence-column974_e2b911-fe > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_e2b911-fe > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_e2b911-fe > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_e2b911-fe > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_e2b911-fe > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_e2b911-fe{position:relative;}@media all and (max-width: 1024px){.kadence-column974_e2b911-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_e2b911-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_e2b911-fe inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_4baefb-1a > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_4baefb-1a > .kt-inside-inner-col,.kadence-column974_4baefb-1a > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_4baefb-1a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_4baefb-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_4baefb-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_4baefb-1a > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_4baefb-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_4baefb-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column974_4baefb-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_4baefb-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_4baefb-1a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_f943e7-5d, .wp-block-kadence-advancedheading.kt-adv-heading974_f943e7-5d[data-kb-block=\"kb-adv-heading974_f943e7-5d\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_f943e7-5d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_f943e7-5d[data-kb-block=\"kb-adv-heading974_f943e7-5d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_f943e7-5d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_f943e7-5d[data-kb-block=\"kb-adv-heading974_f943e7-5d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_f943e7-5d wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_f943e7-5d\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>80<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_52b340-4e, .wp-block-kadence-advancedheading.kt-adv-heading974_52b340-4e[data-kb-block=\"kb-adv-heading974_52b340-4e\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_52b340-4e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_52b340-4e[data-kb-block=\"kb-adv-heading974_52b340-4e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_52b340-4e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_52b340-4e[data-kb-block=\"kb-adv-heading974_52b340-4e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_52b340-4e wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_52b340-4e\"><strong><s>\u00a3<\/s>60<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f3ccfd-a2:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f3ccfd-a2 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f3ccfd-a2 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_f3ccfd-a2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_f3ccfd-a2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_f3ccfd-a2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_f3ccfd-a2 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_b0907d-5c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b0907d-5c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b0907d-5c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_132dbe-65 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_132dbe-65 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_132dbe-65 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6feac2-d7 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6feac2-d7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6feac2-d7 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_315cf7-a5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_315cf7-a5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_315cf7-a5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_a223d6-12 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_a223d6-12 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_a223d6-12 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_2fa840-84 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_2fa840-84 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_2fa840-84 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f8a50d-86 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f8a50d-86 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f8a50d-86 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_d32efa-53 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_d32efa-53 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_d32efa-53 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_31a082-6f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_31a082-6f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_31a082-6f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_fc52e1-46{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_fc52e1-46 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_fc52e1-46\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_2a7183-45.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_2a7183-45 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_31dc12-15 > .kt-inside-inner-col,.kadence-column974_31dc12-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_31dc12-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_31dc12-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_31dc12-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_31dc12-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_31dc12-15{position:relative;}@media all and (max-width: 1024px){.kadence-column974_31dc12-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_31dc12-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_31dc12-15 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_615d4d-29 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_615d4d-29 > .kt-inside-inner-col,.kadence-column974_615d4d-29 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_615d4d-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_615d4d-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_615d4d-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_615d4d-29 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_615d4d-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_615d4d-29{position:relative;}@media all and (max-width: 1024px){.kadence-column974_615d4d-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_615d4d-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_615d4d-29 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_37389c-43, .wp-block-kadence-advancedheading.kt-adv-heading974_37389c-43[data-kb-block=\"kb-adv-heading974_37389c-43\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_37389c-43 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_37389c-43[data-kb-block=\"kb-adv-heading974_37389c-43\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_37389c-43 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_37389c-43[data-kb-block=\"kb-adv-heading974_37389c-43\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_37389c-43 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_37389c-43\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>100<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_df1370-f4, .wp-block-kadence-advancedheading.kt-adv-heading974_df1370-f4[data-kb-block=\"kb-adv-heading974_df1370-f4\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_df1370-f4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_df1370-f4[data-kb-block=\"kb-adv-heading974_df1370-f4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_df1370-f4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_df1370-f4[data-kb-block=\"kb-adv-heading974_df1370-f4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_df1370-f4 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_df1370-f4\"><strong><s>\u00a3<\/s>80<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_103c0d-e0:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_103c0d-e0 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_103c0d-e0 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_103c0d-e0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_103c0d-e0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_103c0d-e0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_103c0d-e0 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_23f4b8-1b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_23f4b8-1b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_23f4b8-1b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_46ce36-91 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_46ce36-91 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_46ce36-91 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_a77ae8-19 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_a77ae8-19 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_a77ae8-19 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_daf222-da .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_daf222-da .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_daf222-da kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_54ee54-5f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_54ee54-5f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_54ee54-5f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c39508-a0 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c39508-a0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c39508-a0 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_98cc80-20 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_98cc80-20 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_98cc80-20 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_9eafa1-70 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_9eafa1-70 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_9eafa1-70 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_6a5872-61 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_6a5872-61 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_6a5872-61 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_eb97d7-e8{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_eb97d7-e8 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_eb97d7-e8\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_1c137e-cb.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_1c137e-cb kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab1d1c1f-22\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id974_bfa17c-8a > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id974_bfa17c-8a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id974_bfa17c-8a .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_bfa17c-8a alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column974_dd6c93-db > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_dd6c93-db > .kt-inside-inner-col,.kadence-column974_dd6c93-db > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_dd6c93-db > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_dd6c93-db > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_dd6c93-db > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_dd6c93-db > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_dd6c93-db > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_dd6c93-db{position:relative;}@media all and (max-width: 1024px){.kadence-column974_dd6c93-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_dd6c93-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_dd6c93-db inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_f82239-1a, .wp-block-kadence-advancedheading.kt-adv-heading974_f82239-1a[data-kb-block=\"kb-adv-heading974_f82239-1a\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_f82239-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_f82239-1a[data-kb-block=\"kb-adv-heading974_f82239-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_f82239-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_f82239-1a[data-kb-block=\"kb-adv-heading974_f82239-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_f82239-1a wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_f82239-1a\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>30<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_f2f9bf-e8, .wp-block-kadence-advancedheading.kt-adv-heading974_f2f9bf-e8[data-kb-block=\"kb-adv-heading974_f2f9bf-e8\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_f2f9bf-e8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_f2f9bf-e8[data-kb-block=\"kb-adv-heading974_f2f9bf-e8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_f2f9bf-e8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_f2f9bf-e8[data-kb-block=\"kb-adv-heading974_f2f9bf-e8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_f2f9bf-e8 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_f2f9bf-e8\"><strong><s>\u00a3<\/s>22<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_080dfe-f0:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_080dfe-f0 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_080dfe-f0 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_080dfe-f0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_080dfe-f0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_080dfe-f0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_080dfe-f0 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_cdeb21-a2 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_cdeb21-a2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_cdeb21-a2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_cfbb81-53 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_cfbb81-53 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_cfbb81-53 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_2e0235-11 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_2e0235-11 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_2e0235-11 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_91ea5f-33 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_91ea5f-33 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_91ea5f-33 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_0c8f21-28 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_0c8f21-28 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_0c8f21-28 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_eed804-82 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_eed804-82 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_eed804-82 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_fc1483-bd .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_fc1483-bd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_fc1483-bd kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_b73551-69 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_b73551-69 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_b73551-69 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_73fd0f-96 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_73fd0f-96 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_73fd0f-96 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_45f0b5-d8{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_45f0b5-d8 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_45f0b5-d8\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_a9e716-0f.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_a9e716-0f kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_f5cada-2f > .kt-inside-inner-col,.kadence-column974_f5cada-2f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_f5cada-2f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f5cada-2f > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f5cada-2f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f5cada-2f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f5cada-2f{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f5cada-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f5cada-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f5cada-2f inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_af5ce1-2f > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_af5ce1-2f > .kt-inside-inner-col,.kadence-column974_af5ce1-2f > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_af5ce1-2f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_af5ce1-2f > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_af5ce1-2f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_af5ce1-2f > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_af5ce1-2f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_af5ce1-2f{position:relative;}@media all and (max-width: 1024px){.kadence-column974_af5ce1-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_af5ce1-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_af5ce1-2f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_587002-3b, .wp-block-kadence-advancedheading.kt-adv-heading974_587002-3b[data-kb-block=\"kb-adv-heading974_587002-3b\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_587002-3b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_587002-3b[data-kb-block=\"kb-adv-heading974_587002-3b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_587002-3b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_587002-3b[data-kb-block=\"kb-adv-heading974_587002-3b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_587002-3b wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_587002-3b\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>60<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_d73376-ea, .wp-block-kadence-advancedheading.kt-adv-heading974_d73376-ea[data-kb-block=\"kb-adv-heading974_d73376-ea\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_d73376-ea mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_d73376-ea[data-kb-block=\"kb-adv-heading974_d73376-ea\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_d73376-ea img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_d73376-ea[data-kb-block=\"kb-adv-heading974_d73376-ea\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_d73376-ea wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_d73376-ea\"><strong><s>\u00a3<\/s>45<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89057e-c8:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89057e-c8 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89057e-c8 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89057e-c8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_89057e-c8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_89057e-c8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_89057e-c8 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_c4b5fc-b1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c4b5fc-b1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c4b5fc-b1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_2944a4-e8 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_2944a4-e8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_2944a4-e8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_18e09e-ba .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_18e09e-ba .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_18e09e-ba kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_261767-d9 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_261767-d9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_261767-d9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_375a8c-e2 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_375a8c-e2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_375a8c-e2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c97929-6b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c97929-6b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c97929-6b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_524d06-c8 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_524d06-c8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_524d06-c8 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_bcebfd-b7 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_bcebfd-b7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_bcebfd-b7 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_7e31c6-bf .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_7e31c6-bf .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_7e31c6-bf kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_e6aacc-19{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_e6aacc-19 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_e6aacc-19\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_d590f1-16.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_d590f1-16 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_ef38e6-5f > .kt-inside-inner-col,.kadence-column974_ef38e6-5f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_ef38e6-5f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_ef38e6-5f > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_ef38e6-5f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_ef38e6-5f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_ef38e6-5f{position:relative;}@media all and (max-width: 1024px){.kadence-column974_ef38e6-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_ef38e6-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_ef38e6-5f inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_e9b6e4-1c > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_e9b6e4-1c > .kt-inside-inner-col,.kadence-column974_e9b6e4-1c > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_e9b6e4-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_e9b6e4-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_e9b6e4-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_e9b6e4-1c > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_e9b6e4-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_e9b6e4-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column974_e9b6e4-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_e9b6e4-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_e9b6e4-1c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_532c05-45, .wp-block-kadence-advancedheading.kt-adv-heading974_532c05-45[data-kb-block=\"kb-adv-heading974_532c05-45\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_532c05-45 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_532c05-45[data-kb-block=\"kb-adv-heading974_532c05-45\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_532c05-45 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_532c05-45[data-kb-block=\"kb-adv-heading974_532c05-45\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_532c05-45 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_532c05-45\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>120<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_274325-93, .wp-block-kadence-advancedheading.kt-adv-heading974_274325-93[data-kb-block=\"kb-adv-heading974_274325-93\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_274325-93 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_274325-93[data-kb-block=\"kb-adv-heading974_274325-93\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_274325-93 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_274325-93[data-kb-block=\"kb-adv-heading974_274325-93\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_274325-93 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_274325-93\"><strong><s>\u00a3<\/s><\/strong>90<\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b2470d-6c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b2470d-6c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b2470d-6c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_b2470d-6c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_b2470d-6c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_b2470d-6c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_b2470d-6c kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_4cdea8-cd .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_4cdea8-cd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_4cdea8-cd kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_432bfc-c5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_432bfc-c5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_432bfc-c5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e8a585-80 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e8a585-80 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e8a585-80 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_63913f-a2 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_63913f-a2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_63913f-a2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e7c01d-47 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e7c01d-47 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e7c01d-47 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_9901da-69 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_9901da-69 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_9901da-69 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f683f3-f4 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f683f3-f4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f683f3-f4 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_54b482-22 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_54b482-22 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_54b482-22 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_636f8d-82 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_636f8d-82 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_636f8d-82 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_3ce2ed-fb{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_3ce2ed-fb .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_3ce2ed-fb\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_305f7a-47.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_305f7a-47 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column974_399b8c-c0 > .kt-inside-inner-col,.kadence-column974_399b8c-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_399b8c-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_399b8c-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_399b8c-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_399b8c-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_399b8c-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column974_399b8c-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_399b8c-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_399b8c-c0 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column974_f7be24-35 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column974_f7be24-35 > .kt-inside-inner-col,.kadence-column974_f7be24-35 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column974_f7be24-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_f7be24-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_f7be24-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_f7be24-35 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column974_f7be24-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_f7be24-35{position:relative;}@media all and (max-width: 1024px){.kadence-column974_f7be24-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_f7be24-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_f7be24-35 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading974_885669-57, .wp-block-kadence-advancedheading.kt-adv-heading974_885669-57[data-kb-block=\"kb-adv-heading974_885669-57\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading974_885669-57 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_885669-57[data-kb-block=\"kb-adv-heading974_885669-57\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_885669-57 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_885669-57[data-kb-block=\"kb-adv-heading974_885669-57\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading974_885669-57 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_885669-57\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><s><s>\u00a3<\/s>150<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading974_c079c8-b6, .wp-block-kadence-advancedheading.kt-adv-heading974_c079c8-b6[data-kb-block=\"kb-adv-heading974_c079c8-b6\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading974_c079c8-b6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading974_c079c8-b6[data-kb-block=\"kb-adv-heading974_c079c8-b6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading974_c079c8-b6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading974_c079c8-b6[data-kb-block=\"kb-adv-heading974_c079c8-b6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading974_c079c8-b6 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading974_c079c8-b6\"><strong><s>\u00a3<\/s>110<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89b0e3-5d:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89b0e3-5d ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89b0e3-5d ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items974_89b0e3-5d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items974_89b0e3-5d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items974_89b0e3-5d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items974_89b0e3-5d kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-974_4ed3db-60 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_4ed3db-60 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_4ed3db-60 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_bc5c59-03 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_bc5c59-03 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_bc5c59-03 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_c3987b-37 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_c3987b-37 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_c3987b-37 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_5c9c68-f3 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_5c9c68-f3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_5c9c68-f3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_e9d05a-cc .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_e9d05a-cc .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_e9d05a-cc kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_838d7d-1d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_838d7d-1d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_838d7d-1d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_3e05bd-f3 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_3e05bd-f3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_3e05bd-f3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_1a935b-ea .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_1a935b-ea .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_1a935b-ea kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-974_f24eec-c1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-974_f24eec-c1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-974_f24eec-c1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_54e522-bd{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_54e522-bd .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_54e522-bd\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn974_046e67-dc.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn974_046e67-dc kt-btn-size-standard kt-btn-width-type-full kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id974_5e86d6-5a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id974_5e86d6-5a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id974_5e86d6-5a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id974_5e86d6-5a{background-image:linear-gradient(135deg,rgb(13,180,233) 0%,var(--global-palette2,#2B6CB0) 50%);}.kb-row-layout-id974_5e86d6-5a > .kt-row-layout-overlay{opacity:0.30;background-color:var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-row-layout-id974_5e86d6-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id974_5e86d6-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id974_5e86d6-5a alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column974_3e6f68-6e > .kt-inside-inner-col,.kadence-column974_3e6f68-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_3e6f68-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_3e6f68-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_3e6f68-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_3e6f68-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_3e6f68-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column974_3e6f68-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_3e6f68-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_3e6f68-6e\"><div class=\"kt-inside-inner-col\">\n<h2 id=\"h-how-to-setup-iptv-on-your-device\" class=\"wp-block-heading has-large-font-size\" style=\"text-transform:capitalize\">How to setup IPTV on your Device<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column974_8ab5d9-34 > .kt-inside-inner-col,.kadence-column974_8ab5d9-34 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column974_8ab5d9-34 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column974_8ab5d9-34 > .kt-inside-inner-col{flex-direction:column;}.kadence-column974_8ab5d9-34 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column974_8ab5d9-34 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column974_8ab5d9-34{position:relative;}@media all and (max-width: 1024px){.kadence-column974_8ab5d9-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column974_8ab5d9-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column974_8ab5d9-34\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns974_a57336-34{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_a57336-34 .kt-button{font-weight:normal;font-style:normal;}.kt-btns974_a57336-34 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns974_a57336-34 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns974_a57336-34 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns974_a57336-34 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns974_a57336-34 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns974_a57336-34 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns974_a57336-34 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_a57336-34\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_cd1b98-40.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn974_cd1b98-40 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/dgtl-planet.media\/tutorials\/\"><span class=\"kt-btn-inner-text\">Tutorials<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center has-small-font-size is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:5px;padding-bottom:5px;flex-basis:100%\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-4-color has-text-color has-background has-large-font-size wp-block-paragraph\" style=\"background-color:#edf2f700;padding-top:1px;padding-right:1px;padding-bottom:1px;padding-left:1px\"><strong>Testimonials from our valued clients<\/strong><\/p>\n\n\n\n<div class=\"wp-block-carousel-slider-slider\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-6256\" style=\"--carousel-slider-nav-color:rgba(241,241,241,0);--carousel-slider-active-nav-color:rgba(0,209,178,0);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-6256\" class=\"carousel-slider carousel-slider-6256 arrows-visibility-never dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":false,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":3000,\"autoplaySpeed\":2000,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":2},\"576\":{\"items\":3},\"768\":{\"items\":3},\"1024\":{\"items\":4},\"1280\":{\"items\":4},\"1536\":{\"items\":4}}}'>\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1.jpg\" data-width=\"921\" data-height=\"2048\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"2048\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1.jpg 921w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-135x300.jpg 135w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-461x1024.jpg 461w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-768x1708.jpg 768w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-691x1536.jpg 691w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-5x12.jpg 5w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-700x1557.jpg 700w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/10.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/10.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/10.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/10-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/6.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/6.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/6.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/6-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/20.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/20.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/20.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/20-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/4.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/4.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/4.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/4-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/16.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/16.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/16.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/16-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/2.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/2.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/2.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/2-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/19.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/19.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/19.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/19-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/3.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/3.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/3.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/3-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/17.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/17.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/17.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/17-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/15.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/15.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/15.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/15-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/12.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/12.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/12.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/12-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/5.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/5.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/5.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/5-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/1.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/1.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/1.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/1-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/8.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/8.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/8.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/8-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/9.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/9.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/9.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/9-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/11.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/11.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/11.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/11-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/13.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/13.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/13.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/13-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/18.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/18.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/18.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/18-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/14.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/14.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/14.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/14-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/7.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/7.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/7.webp 500w, https:\/\/dgtl-planet.media\/wp-content\/uploads\/2023\/06\/7-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<\/div><!-- .carousel-slider-6256 -->\n<\/div><!-- .carousel-slider-outer-6256 -->\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_37411f-bf{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_37411f-bf .kt-button{font-weight:normal;font-style:normal;}.kt-btns974_37411f-bf .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns974_37411f-bf .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns974_37411f-bf .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns974_37411f-bf .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns974_37411f-bf .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns974_37411f-bf .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns974_37411f-bf .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_37411f-bf\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_36bc1e-6e.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_36bc1e-6e.kb-button{color:#ffffff;background:#27db36;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px var(--global-palette4, #2D3748);}.kb-btn974_36bc1e-6e.kb-button .kb-svg-icon-wrap{font-size:34px;--kb-button-icon-size:34px;}<\/style><a class=\"kb-button kt-button button kb-btn974_36bc1e-6e kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_whatsapp kt-btn-icon-side-left\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Share your Feedback<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_c25300-ed.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_c25300-ed.kb-button{color:#ffffff;background:#0088cc;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px var(--global-palette4, #2D3748);}.kb-btn974_c25300-ed.kb-button .kb-svg-icon-wrap{font-size:34px;--kb-button-icon-size:34px;}<\/style><a class=\"kb-button kt-button button kb-btn974_c25300-ed kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"http:\/\/bit.ly\/44rQgpM\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_telegram kt-btn-icon-side-left\"><svg viewBox=\"0 0 496 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm121.8 169.9l-40.7 191.8c-3 13.6-11.1 16.9-22.4 10.5l-62-45.7-29.9 28.8c-3.3 3.3-6.1 6.1-12.5 6.1l4.4-63.1 114.9-103.8c5-4.4-1.1-6.9-7.7-2.5l-142 89.4-61.2-19.1c-13.3-4.2-13.6-13.3 2.8-19.7l239.1-92.2c11.1-4 20.8 2.7 17.2 19.5z\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Join Our Telegram Channel<\/span><\/a><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns974_489646-f7{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns974_489646-f7 .kt-button{font-weight:normal;font-style:normal;}.kt-btns974_489646-f7 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns974_489646-f7 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns974_489646-f7 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns974_489646-f7 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns974_489646-f7 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns974_489646-f7 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns974_489646-f7 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns974_489646-f7\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn974_3f9f70-d2.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn974_3f9f70-d2.kb-button{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}<\/style><a class=\"kb-button kt-button button kb-btn974_3f9f70-d2 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/wa.link\/digitalplanet\"><span class=\"kt-btn-inner-text\">\u267b\ufe0f RENEW YOUR SUBSCRIPTION! \u267b\ufe0f<\/span><\/a><\/div>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bir Abonelik Plan\u0131 Se\u00e7in Cihaz\u0131n\u0131za IPTV nas\u0131l kurulur De\u011ferli m\u00fc\u015fterilerimizden referanslar<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"default","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[],"footnotes":""},"class_list":["post-974","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/pages\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/comments?post=974"}],"version-history":[{"count":517,"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/pages\/974\/revisions"}],"predecessor-version":[{"id":12812,"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/pages\/974\/revisions\/12812"}],"wp:attachment":[{"href":"https:\/\/dgtl-planet.media\/turkce_iptv\/wp-json\/wp\/v2\/media?parent=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}